{"id":3955,"date":"2022-12-21T11:38:53","date_gmt":"2022-12-21T16:38:53","guid":{"rendered":"https:\/\/skimarathon.ca\/?page_id=3955"},"modified":"2022-12-22T12:38:48","modified_gmt":"2022-12-22T17:38:48","slug":"prix-speciaux-2023","status":"publish","type":"page","link":"https:\/\/skimarathon.ca\/fr\/resultats\/prix-speciaux-2023\/","title":{"rendered":"Prix sp\u00e9ciaux 2023"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3955\" class=\"elementor elementor-3955\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"ob-is-breaking-bad elementor-section elementor-top-section elementor-element elementor-element-b962f93 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"b962f93\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_bbad_use_it&quot;:&quot;yes&quot;,&quot;_ob_bbad_sssic_use&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33d7007\" data-id=\"33d7007\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_bbad_is_stalker&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b73fd2 elementor-widget elementor-widget-heading\" data-id=\"1b73fd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prix sp\u00e9ciaux 2023<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"ob-is-breaking-bad elementor-section elementor-top-section elementor-element elementor-element-ddb237e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddb237e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_bbad_use_it&quot;:&quot;yes&quot;,&quot;_ob_bbad_sssic_use&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5cfbd73\" data-id=\"5cfbd73\" data-element_type=\"column\" data-e-type=\"column\" id=\"custom_data_table\" data-settings=\"{&quot;_ob_bbad_is_stalker&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd5df1c elementor-tabs-alignment-center elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"cd5df1c\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"custom_data_table\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2151\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2151\" aria-expanded=\"false\">Les CdB l\u00e9gendaires<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2152\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2152\" aria-expanded=\"false\">Prix Weber<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2153\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2153\" aria-expanded=\"false\">Prix en fonction de l'\u00e2ge<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2154\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2154\" aria-expanded=\"false\">Jeunes de Coeur<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2151\" aria-expanded=\"false\">Les CdB l\u00e9gendaires<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2151\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2151\" tabindex=\"0\" hidden=\"false\"><h3><strong>Or<\/strong><\/h3>\n<table id=\"tablepress-3\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">501<\/td><td class=\"column-2\">Morris Manolson<\/td><td class=\"column-3\">Toronto, Ontario<\/td><td class=\"column-4\">64<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">503<\/td><td class=\"column-2\">Becca Carroll<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">50<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">505<\/td><td class=\"column-2\">Ian Waugh<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">48<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">593<\/td><td class=\"column-2\">Mark Isselhardt<\/td><td class=\"column-3\">Wolcott, Vermont<\/td><td class=\"column-4\">47<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">533<\/td><td class=\"column-2\">Frederic Dallaire<\/td><td class=\"column-3\">Val-David, Quebec<\/td><td class=\"column-4\">36<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">579<\/td><td class=\"column-2\">Zacharie Turgeon<\/td><td class=\"column-3\">Ville de Qu\u00e9bec, Quebec<\/td><td class=\"column-4\">27<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">553<\/td><td class=\"column-2\">Olivier Lapointe<\/td><td class=\"column-3\">Gatineau, Quebec<\/td><td class=\"column-4\">26<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">9019<\/td><td class=\"column-2\">Aidan Raynor<\/td><td class=\"column-3\">Beaconsfield, Quebec<\/td><td class=\"column-4\">19<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3 from cache --><h3><strong>Platine<\/strong><\/h3>\n<table id=\"tablepress-3-no-2\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">376<\/td><td class=\"column-2\">Paul Ukrainetz<\/td><td class=\"column-3\">Pointe Claire, Quebec<\/td><td class=\"column-4\">59<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">348<\/td><td class=\"column-2\">Megan MacDonald<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">40<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">370<\/td><td class=\"column-2\">Ruth McGovern<\/td><td class=\"column-3\">Stowe, Vermont<\/td><td class=\"column-4\">34<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-2 from cache --><h3><strong>Double Platine<\/strong><\/h3>\n<table id=\"tablepress-3-no-3\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-3 from cache --><h3><strong>Triple Platine<\/strong><\/h3>\n<table id=\"tablepress-3-no-4\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-4 from cache --><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2152\" aria-expanded=\"false\">Prix Weber<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2152\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2152\" tabindex=\"0\" hidden=\"hidden\"><h3><strong>Femmes<\/strong><\/h3>\n<table id=\"tablepress-3-no-5\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-5 from cache --><h3><strong>Hommes<\/strong><\/h3>\n<table id=\"tablepress-3-no-6\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-6 from cache --><p>\u00a0<\/p><p>\u00a0<\/p><p><strong>Le prix Weber est gagn\u00e9 par un Randonneur qui a ski\u00e9 un total de 50 sections ou plus depuis 1996. &lt;br&gt;<\/strong><br \/><strong>Le skieur re\u00e7oit un num\u00e9ro permanent qui sera port\u00e9 sur un dossard de couleur rose.<\/strong><br \/><strong>Un randonneur prendra en moyenne au moins 7 ans \u00e0 atteindre ce niveau de performance, l&rsquo;\u00e9quivalent du <\/strong><br \/><strong>nombre d&rsquo;ann\u00e9es requis par un Coureur des Bois pour obtenir son dossard permanent Or.<\/strong><br \/><strong>Le prix est nomm\u00e9 d&rsquo;apr\u00e8s Hans et Meg Weber qui ont ski\u00e9 le MCS depuis ses d\u00e9buts.<\/strong><\/p><p><strong>Si vous avez atteint le plateau des 50 sections svp communiquez avec le bureau du MCS pour qu\u2019un num\u00e9ro de dossard permanent rose vous soit assign\u00e9 !<\/strong><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2153\" aria-expanded=\"false\">Prix en fonction de l'\u00e2ge<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2153\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2153\" tabindex=\"0\" hidden=\"hidden\"><h3><strong>Plus jeune fille \u00e0 obtenir un prix<\/strong><\/h3>\n<table id=\"tablepress-3-no-7\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">9340<\/td><td class=\"column-2\">Kalinda Erven<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-7 from cache --><h3><strong>Plus jeune gar\u00e7on \u00e0 obtenir un prix<\/strong><\/h3>\n<table id=\"tablepress-3-no-8\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1551<\/td><td class=\"column-2\">F\u00e9lix Dion<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">8<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">5049<\/td><td class=\"column-2\">Zephyr Mills Throop-Hale<\/td><td class=\"column-3\">Chelsea, Quebec<\/td><td class=\"column-4\">8<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-8 from cache --><h3><strong>Femme la plus \u00e2g\u00e9e \u00e0 obtenir un prix<\/strong><\/h3>\n<table id=\"tablepress-3-no-9\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">2113<\/td><td class=\"column-2\">Mary Muse<\/td><td class=\"column-3\">Elmira, New York<\/td><td class=\"column-4\">70<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-9 from cache --><h3><strong>Homme le plus \u00e2g\u00e9 \u00e0 obtenir un prix<\/strong><\/h3>\n<table id=\"tablepress-3-no-10\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-10 from cache --><h3><strong>Prix comm\u00e9moratif Hugh Blanchford<\/strong><\/h3><p><strong>Femme la plus \u00e2g\u00e9e \u00e0 avoir compl\u00e9t\u00e9 la cat\u00e9gorie Coureur des Bois<\/strong><\/p>\n<table id=\"tablepress-3-no-11\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">132<\/td><td class=\"column-2\">Christiane Rousseau<\/td><td class=\"column-3\">Mont-Saint-Gr\u00e9goire, Quebec<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-11 from cache --><h3><strong>Prix comm\u00e9moratif Hugh Blanchford<\/strong><\/h3><p><strong>Homme le plus \u00e2g\u00e9 \u00e0 avoir compl\u00e9t\u00e9 la cat\u00e9gorie Coureur des Bois<\/strong><br \/>\n<table id=\"tablepress-3-no-12\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">Brian Gill<\/td><td class=\"column-3\">Morin-Heights, Quebec<\/td><td class=\"column-4\">79<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-12 from cache --><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2154\" aria-expanded=\"false\">Jeunes de Coeur<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2154\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2154\" tabindex=\"0\" hidden=\"hidden\"><h3><strong>Prix Jeunes de Coeur <\/strong><\/h3><p><strong>65 ans et plus &lt;br&gt;a ski\u00e9 4 sections ou plus<\/strong><\/p>\n<table id=\"tablepress-3-no-13\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">2037<\/th><th class=\"column-2\">Pierre Lortie<\/th><th class=\"column-3\">Qu\u00e9bec, Quebec<\/th><th class=\"column-4\">83<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">2105<\/td><td class=\"column-2\">John Blachford<\/td><td class=\"column-3\">Montreal, Quebec<\/td><td class=\"column-4\">86<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">Brian Gill<\/td><td class=\"column-3\">Morin-Heights, Quebec<\/td><td class=\"column-4\">79<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">158<\/td><td class=\"column-2\">Stephen Walter<\/td><td class=\"column-3\">Oakville, Ontario<\/td><td class=\"column-4\">75<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">9110<\/td><td class=\"column-2\">Alexander Vologodskii<\/td><td class=\"column-3\">New York, New York<\/td><td class=\"column-4\">75<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">1513<\/td><td class=\"column-2\">Jonas Barter<\/td><td class=\"column-3\">Almonte, Ontario<\/td><td class=\"column-4\">74<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">9098<\/td><td class=\"column-2\">Gary Rennie<\/td><td class=\"column-3\">Tecumseh, Ontario<\/td><td class=\"column-4\">74<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">2042<\/td><td class=\"column-2\">Linda Haines<\/td><td class=\"column-3\">Northfield, New Hampshire<\/td><td class=\"column-4\">73<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">2040<\/td><td class=\"column-2\">Paul Gross<\/td><td class=\"column-3\">Norwich, Vermont<\/td><td class=\"column-4\">72<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">528<\/td><td class=\"column-2\">Tomoko Murakami<\/td><td class=\"column-3\">Ann Arbor, Michigan<\/td><td class=\"column-4\">71<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">256<\/td><td class=\"column-2\">Alain Giguere<\/td><td class=\"column-3\">Laval, Quebec<\/td><td class=\"column-4\">71<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">1521<\/td><td class=\"column-2\">Gilles Whear<\/td><td class=\"column-3\">Mont-Laurier, Quebec<\/td><td class=\"column-4\">70<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">238<\/td><td class=\"column-2\">Marvin Boluyt<\/td><td class=\"column-3\">Ann Arbor, Michigan<\/td><td class=\"column-4\">70<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">2113<\/td><td class=\"column-2\">Mary Muse<\/td><td class=\"column-3\">Elmira, New York<\/td><td class=\"column-4\">70<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">132<\/td><td class=\"column-2\">Christiane Rousseau<\/td><td class=\"column-3\">Mont-Saint-Gr\u00e9goire, Quebec<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">315<\/td><td class=\"column-2\">Scott McGovern<\/td><td class=\"column-3\">Peterborough, New Hampshire<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">4000<\/td><td class=\"column-2\">Edith Forbes<\/td><td class=\"column-3\">Norwich, Vermont<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">9178<\/td><td class=\"column-2\">Gilles Saulnier<\/td><td class=\"column-3\">Morin-Heights, Quebec<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">2060<\/td><td class=\"column-2\">David LaCoste<\/td><td class=\"column-3\">Keene, New Hampshire<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">2070<\/td><td class=\"column-2\">Elaine Maheu<\/td><td class=\"column-3\">Laval, Quebec<\/td><td class=\"column-4\">68<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">2019<\/td><td class=\"column-2\">Andrew Plank<\/td><td class=\"column-3\">Montreal, Quebec<\/td><td class=\"column-4\">68<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">6008<\/td><td class=\"column-2\">Peggy Brown<\/td><td class=\"column-3\">Peterborough, New Hampshire<\/td><td class=\"column-4\">68<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">434<\/td><td class=\"column-2\">David Sherrard<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">166<\/td><td class=\"column-2\">Parham Momtahan<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">2209<\/td><td class=\"column-2\">Denis Bouchard<\/td><td class=\"column-3\">Dolbeau-Mistassini, Quebec<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">1581<\/td><td class=\"column-2\">Greg Cooper<\/td><td class=\"column-3\">Bancroft, Ontario<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">9180<\/td><td class=\"column-2\">Kathryn Knowles<\/td><td class=\"column-3\">Winnipeg, Manitoba<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">2231<\/td><td class=\"column-2\">Barbara Lewis<\/td><td class=\"column-3\">Ste. Agathe-des-Monts, Quebec<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">240<\/td><td class=\"column-2\">Pierre Lheureux<\/td><td class=\"column-3\">Montreal, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">291<\/td><td class=\"column-2\">Gilles Cloutier<\/td><td class=\"column-3\">Gatineau, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">1537<\/td><td class=\"column-2\">France C\u00f4t\u00e9<\/td><td class=\"column-3\">Lac-Beauport, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">1042<\/td><td class=\"column-2\">Scott Morgan<\/td><td class=\"column-3\">Westmount, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">9038<\/td><td class=\"column-2\">Daniel Boudreau<\/td><td class=\"column-3\">St-C\u00f4me, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">1511<\/td><td class=\"column-2\">Karin Tilberg<\/td><td class=\"column-3\">Salsbury Cove, Maine<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">2050<\/td><td class=\"column-2\">Greg Wooster<\/td><td class=\"column-3\">Ithaca, New York<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">590<\/td><td class=\"column-2\">Daniel Locas<\/td><td class=\"column-3\">Chelsea, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">9032<\/td><td class=\"column-2\">Sherri Audet<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">2233<\/td><td class=\"column-2\">Michel Dub\u00e9<\/td><td class=\"column-3\">Drummondville, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">3008<\/td><td class=\"column-2\">Martine Schwab<\/td><td class=\"column-3\">Granby, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">414<\/td><td class=\"column-2\">Harris Kirby<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">38<\/td><td class=\"column-2\">Luc Farmer<\/td><td class=\"column-3\">Notre Dame de la Merci, Quebec<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">1529<\/td><td class=\"column-2\">Susan Pierce<\/td><td class=\"column-3\">Ogdensburg, New York<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">228<\/td><td class=\"column-2\">John Hogg<\/td><td class=\"column-3\">Port Sydney, Ontario<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">2281<\/td><td class=\"column-2\">Lynn Morgan<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">2103<\/td><td class=\"column-2\">Lori Baird<\/td><td class=\"column-3\">Westmount, Quebec<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">2204<\/td><td class=\"column-2\">Stephen Cater<\/td><td class=\"column-3\">Scarborough, Ontario<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">9154<\/td><td class=\"column-2\">Sharon Braverman<\/td><td class=\"column-3\">Montreal, Quebec<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">2237<\/td><td class=\"column-2\">Paul Pierce<\/td><td class=\"column-3\">Ogdensburg, New York<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">9186<\/td><td class=\"column-2\">Cecilia Malinski<\/td><td class=\"column-3\">Montr\u00e9al-Ouest, Quebec<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-13 from cache --><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a535e1f elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-widget elementor-widget-toggle\" data-id=\"a535e1f\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"custom_data_table\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1731\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1731\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les CdB l\u00e9gendaires<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1731\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1731\"><h3><strong>Or<\/strong><\/h3>\n\n<table id=\"tablepress-3-no-14\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">501<\/td><td class=\"column-2\">Morris Manolson<\/td><td class=\"column-3\">Toronto, Ontario<\/td><td class=\"column-4\">64<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">503<\/td><td class=\"column-2\">Becca Carroll<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">50<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">505<\/td><td class=\"column-2\">Ian Waugh<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">48<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">593<\/td><td class=\"column-2\">Mark Isselhardt<\/td><td class=\"column-3\">Wolcott, Vermont<\/td><td class=\"column-4\">47<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">533<\/td><td class=\"column-2\">Frederic Dallaire<\/td><td class=\"column-3\">Val-David, Quebec<\/td><td class=\"column-4\">36<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">579<\/td><td class=\"column-2\">Zacharie Turgeon<\/td><td class=\"column-3\">Ville de Qu\u00e9bec, Quebec<\/td><td class=\"column-4\">27<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">553<\/td><td class=\"column-2\">Olivier Lapointe<\/td><td class=\"column-3\">Gatineau, Quebec<\/td><td class=\"column-4\">26<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">9019<\/td><td class=\"column-2\">Aidan Raynor<\/td><td class=\"column-3\">Beaconsfield, Quebec<\/td><td class=\"column-4\">19<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-14 from cache -->\n<h3><strong>Platine<\/strong><\/h3>\n\n<table id=\"tablepress-3-no-15\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">376<\/td><td class=\"column-2\">Paul Ukrainetz<\/td><td class=\"column-3\">Pointe Claire, Quebec<\/td><td class=\"column-4\">59<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">348<\/td><td class=\"column-2\">Megan MacDonald<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">40<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">370<\/td><td class=\"column-2\">Ruth McGovern<\/td><td class=\"column-3\">Stowe, Vermont<\/td><td class=\"column-4\">34<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-15 from cache -->\n<h3><strong>Double Platine<\/strong><\/h3>\n\n<table id=\"tablepress-3-no-16\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-16 from cache -->\n<h3><strong>Triple Platine<\/strong><\/h3>\n\n<table id=\"tablepress-3-no-17\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-17 from cache --><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1732\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1732\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Prix Weber<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1732\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1732\"><h3><strong>Femmes<\/strong><\/h3>\n\n<table id=\"tablepress-3-no-18\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-18 from cache -->\n<h3><strong>Hommes<\/strong><\/h3>\n\n<table id=\"tablepress-3-no-19\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-19 from cache -->\n\n<strong>Le prix Weber est gagn\u00e9 par un Randonneur qui a ski\u00e9 un total de 50 sections ou plus depuis 1996. &lt;br&gt;<\/strong>\n<strong>Le skieur re\u00e7oit un num\u00e9ro permanent qui sera port\u00e9 sur un dossard de couleur rose.<\/strong>\n<strong>Un randonneur prendra en moyenne au moins 7 ans \u00e0 atteindre ce niveau de performance, l&rsquo;\u00e9quivalent du <\/strong>\n<strong>nombre d&rsquo;ann\u00e9es requis par un Coureur des Bois pour obtenir son dossard permanent Or.<\/strong>\n<strong>Le prix est nomm\u00e9 d&rsquo;apr\u00e8s Hans et Meg Weber qui ont ski\u00e9 le MCS depuis ses d\u00e9buts.<\/strong>\n\n<strong>Si vous avez atteint le plateau des 50 sections svp communiquez avec le bureau du MCS pour qu\u2019un num\u00e9ro de dossard permanent rose vous soit assign\u00e9 !<\/strong><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1733\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1733\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Prix en fonction de l'\u00e2ge<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1733\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1733\"><h3><strong>Plus jeune fille \u00e0 obtenir un prix<\/strong><\/h3>\n\n<table id=\"tablepress-3-no-20\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">9340<\/td><td class=\"column-2\">Kalinda Erven<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-20 from cache -->\n<h3><strong>Plus jeune gar\u00e7on \u00e0 obtenir un prix<\/strong><\/h3>\n\n<table id=\"tablepress-3-no-21\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1551<\/td><td class=\"column-2\">F\u00e9lix Dion<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">8<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">5049<\/td><td class=\"column-2\">Zephyr Mills Throop-Hale<\/td><td class=\"column-3\">Chelsea, Quebec<\/td><td class=\"column-4\">8<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-21 from cache -->\n<h3><strong>Femme la plus \u00e2g\u00e9e \u00e0 obtenir un prix<\/strong><\/h3>\n\n<table id=\"tablepress-3-no-22\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">2113<\/td><td class=\"column-2\">Mary Muse<\/td><td class=\"column-3\">Elmira, New York<\/td><td class=\"column-4\">70<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-22 from cache -->\n<h3><strong>Homme le plus \u00e2g\u00e9 \u00e0 obtenir un prix<\/strong><\/h3>\n\n<table id=\"tablepress-3-no-23\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-23 from cache -->\n<h3><strong>Prix comm\u00e9moratif Hugh Blanchford<\/strong><\/h3>\n<strong>Femme la plus \u00e2g\u00e9e \u00e0 avoir compl\u00e9t\u00e9 la cat\u00e9gorie Coureur des Bois<\/strong>\n\n\n<table id=\"tablepress-3-no-24\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">132<\/td><td class=\"column-2\">Christiane Rousseau<\/td><td class=\"column-3\">Mont-Saint-Gr\u00e9goire, Quebec<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-24 from cache -->\n<h3><strong>Prix comm\u00e9moratif Hugh Blanchford<\/strong><\/h3>\n<strong>Homme le plus \u00e2g\u00e9 \u00e0 avoir compl\u00e9t\u00e9 la cat\u00e9gorie Coureur des Bois<\/strong>\n\n<table id=\"tablepress-3-no-25\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Dossard<\/th><th class=\"column-2\">Nom<\/th><th class=\"column-3\">Adresse<\/th><th class=\"column-4\">\u00c2ge<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">Brian Gill<\/td><td class=\"column-3\">Morin-Heights, Quebec<\/td><td class=\"column-4\">79<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-25 from cache --><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1734\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1734\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Jeunes de Coeur<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1734\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1734\"><h3><strong>Prix Jeunes de Coeur <\/strong><\/h3>\n<strong>65 ans et plus &lt;br&gt;a ski\u00e9 4 sections ou plus<\/strong>\n\n\n<table id=\"tablepress-3-no-26\" class=\"tablepress tablepress-id-3 tablepress-responsive tablepress-responsive-tablet\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">2037<\/th><th class=\"column-2\">Pierre Lortie<\/th><th class=\"column-3\">Qu\u00e9bec, Quebec<\/th><th class=\"column-4\">83<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">2105<\/td><td class=\"column-2\">John Blachford<\/td><td class=\"column-3\">Montreal, Quebec<\/td><td class=\"column-4\">86<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">Brian Gill<\/td><td class=\"column-3\">Morin-Heights, Quebec<\/td><td class=\"column-4\">79<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">158<\/td><td class=\"column-2\">Stephen Walter<\/td><td class=\"column-3\">Oakville, Ontario<\/td><td class=\"column-4\">75<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">9110<\/td><td class=\"column-2\">Alexander Vologodskii<\/td><td class=\"column-3\">New York, New York<\/td><td class=\"column-4\">75<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">1513<\/td><td class=\"column-2\">Jonas Barter<\/td><td class=\"column-3\">Almonte, Ontario<\/td><td class=\"column-4\">74<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">9098<\/td><td class=\"column-2\">Gary Rennie<\/td><td class=\"column-3\">Tecumseh, Ontario<\/td><td class=\"column-4\">74<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">2042<\/td><td class=\"column-2\">Linda Haines<\/td><td class=\"column-3\">Northfield, New Hampshire<\/td><td class=\"column-4\">73<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">2040<\/td><td class=\"column-2\">Paul Gross<\/td><td class=\"column-3\">Norwich, Vermont<\/td><td class=\"column-4\">72<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">528<\/td><td class=\"column-2\">Tomoko Murakami<\/td><td class=\"column-3\">Ann Arbor, Michigan<\/td><td class=\"column-4\">71<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">256<\/td><td class=\"column-2\">Alain Giguere<\/td><td class=\"column-3\">Laval, Quebec<\/td><td class=\"column-4\">71<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">1521<\/td><td class=\"column-2\">Gilles Whear<\/td><td class=\"column-3\">Mont-Laurier, Quebec<\/td><td class=\"column-4\">70<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">238<\/td><td class=\"column-2\">Marvin Boluyt<\/td><td class=\"column-3\">Ann Arbor, Michigan<\/td><td class=\"column-4\">70<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">2113<\/td><td class=\"column-2\">Mary Muse<\/td><td class=\"column-3\">Elmira, New York<\/td><td class=\"column-4\">70<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">132<\/td><td class=\"column-2\">Christiane Rousseau<\/td><td class=\"column-3\">Mont-Saint-Gr\u00e9goire, Quebec<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">315<\/td><td class=\"column-2\">Scott McGovern<\/td><td class=\"column-3\">Peterborough, New Hampshire<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">4000<\/td><td class=\"column-2\">Edith Forbes<\/td><td class=\"column-3\">Norwich, Vermont<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">9178<\/td><td class=\"column-2\">Gilles Saulnier<\/td><td class=\"column-3\">Morin-Heights, Quebec<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">2060<\/td><td class=\"column-2\">David LaCoste<\/td><td class=\"column-3\">Keene, New Hampshire<\/td><td class=\"column-4\">69<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">2070<\/td><td class=\"column-2\">Elaine Maheu<\/td><td class=\"column-3\">Laval, Quebec<\/td><td class=\"column-4\">68<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">2019<\/td><td class=\"column-2\">Andrew Plank<\/td><td class=\"column-3\">Montreal, Quebec<\/td><td class=\"column-4\">68<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">6008<\/td><td class=\"column-2\">Peggy Brown<\/td><td class=\"column-3\">Peterborough, New Hampshire<\/td><td class=\"column-4\">68<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">434<\/td><td class=\"column-2\">David Sherrard<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">166<\/td><td class=\"column-2\">Parham Momtahan<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">2209<\/td><td class=\"column-2\">Denis Bouchard<\/td><td class=\"column-3\">Dolbeau-Mistassini, Quebec<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">1581<\/td><td class=\"column-2\">Greg Cooper<\/td><td class=\"column-3\">Bancroft, Ontario<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">9180<\/td><td class=\"column-2\">Kathryn Knowles<\/td><td class=\"column-3\">Winnipeg, Manitoba<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">2231<\/td><td class=\"column-2\">Barbara Lewis<\/td><td class=\"column-3\">Ste. Agathe-des-Monts, Quebec<\/td><td class=\"column-4\">67<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">240<\/td><td class=\"column-2\">Pierre Lheureux<\/td><td class=\"column-3\">Montreal, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">291<\/td><td class=\"column-2\">Gilles Cloutier<\/td><td class=\"column-3\">Gatineau, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">1537<\/td><td class=\"column-2\">France C\u00f4t\u00e9<\/td><td class=\"column-3\">Lac-Beauport, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">1042<\/td><td class=\"column-2\">Scott Morgan<\/td><td class=\"column-3\">Westmount, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">9038<\/td><td class=\"column-2\">Daniel Boudreau<\/td><td class=\"column-3\">St-C\u00f4me, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">1511<\/td><td class=\"column-2\">Karin Tilberg<\/td><td class=\"column-3\">Salsbury Cove, Maine<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">2050<\/td><td class=\"column-2\">Greg Wooster<\/td><td class=\"column-3\">Ithaca, New York<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">590<\/td><td class=\"column-2\">Daniel Locas<\/td><td class=\"column-3\">Chelsea, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">9032<\/td><td class=\"column-2\">Sherri Audet<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">2233<\/td><td class=\"column-2\">Michel Dub\u00e9<\/td><td class=\"column-3\">Drummondville, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">3008<\/td><td class=\"column-2\">Martine Schwab<\/td><td class=\"column-3\">Granby, Quebec<\/td><td class=\"column-4\">66<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">414<\/td><td class=\"column-2\">Harris Kirby<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">38<\/td><td class=\"column-2\">Luc Farmer<\/td><td class=\"column-3\">Notre Dame de la Merci, Quebec<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">1529<\/td><td class=\"column-2\">Susan Pierce<\/td><td class=\"column-3\">Ogdensburg, New York<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">228<\/td><td class=\"column-2\">John Hogg<\/td><td class=\"column-3\">Port Sydney, Ontario<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">2281<\/td><td class=\"column-2\">Lynn Morgan<\/td><td class=\"column-3\">Ottawa, Ontario<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">2103<\/td><td class=\"column-2\">Lori Baird<\/td><td class=\"column-3\">Westmount, Quebec<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">2204<\/td><td class=\"column-2\">Stephen Cater<\/td><td class=\"column-3\">Scarborough, Ontario<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">9154<\/td><td class=\"column-2\">Sharon Braverman<\/td><td class=\"column-3\">Montreal, Quebec<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">2237<\/td><td class=\"column-2\">Paul Pierce<\/td><td class=\"column-3\">Ogdensburg, New York<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">9186<\/td><td class=\"column-2\">Cecilia Malinski<\/td><td class=\"column-3\">Montr\u00e9al-Ouest, Quebec<\/td><td class=\"column-4\">65<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3-no-26 from cache --><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"ob-is-breaking-bad elementor-section elementor-top-section elementor-element elementor-element-9e758c5 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"9e758c5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_bbad_use_it&quot;:&quot;yes&quot;,&quot;_ob_bbad_sssic_use&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be00bb8\" data-id=\"be00bb8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_bbad_is_stalker&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Les CdB l\u00e9gendaires Prix Weber Prix en fonction de l&rsquo;\u00e2ge Jeunes de Coeur Les CdB l\u00e9gendaires Or Platine Double Platine Triple Platine Prix Weber Femmes Hommes \u00a0 \u00a0 Le prix Weber est gagn\u00e9 par un Randonneur qui a ski\u00e9 un total de 50 sections ou plus depuis 1996. &lt;br&gt;Le skieur re\u00e7oit un num\u00e9ro permanent qui [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3849,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"inline_featured_image":false,"footnotes":""},"class_list":["post-3955","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/skimarathon.ca\/fr\/wp-json\/wp\/v2\/pages\/3955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skimarathon.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/skimarathon.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/skimarathon.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/skimarathon.ca\/fr\/wp-json\/wp\/v2\/comments?post=3955"}],"version-history":[{"count":31,"href":"https:\/\/skimarathon.ca\/fr\/wp-json\/wp\/v2\/pages\/3955\/revisions"}],"predecessor-version":[{"id":4494,"href":"https:\/\/skimarathon.ca\/fr\/wp-json\/wp\/v2\/pages\/3955\/revisions\/4494"}],"up":[{"embeddable":true,"href":"https:\/\/skimarathon.ca\/fr\/wp-json\/wp\/v2\/pages\/3849"}],"wp:attachment":[{"href":"https:\/\/skimarathon.ca\/fr\/wp-json\/wp\/v2\/media?parent=3955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}